{"id":7293,"date":"2025-05-08T09:35:07","date_gmt":"2025-05-08T07:35:07","guid":{"rendered":"https:\/\/info.parcandi.ch\/?p=7293"},"modified":"2026-07-14T17:07:30","modified_gmt":"2026-07-14T15:07:30","slug":"dopo-cinque-anni-di-lavoro-cedric-wichert-lascia-parcandi-ag-desideriamo-ringraziarlo-per-il-suo-impegno-e-augurargli-il-meglio-per-il-futuro","status":"publish","type":"post","link":"https:\/\/info.parcandi.ch\/it\/dopo-cinque-anni-di-lavoro-cedric-wichert-lascia-parcandi-ag-desideriamo-ringraziarlo-per-il-suo-impegno-e-augurargli-il-meglio-per-il-futuro\/","title":{"rendered":"Dopo cinque anni di lavoro, C\u00e9dric Wichert lascia Parcandi AG. Desideriamo ringraziarlo per il suo impegno e augurargli il meglio per il futuro."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"7293\" class=\"elementor elementor-7293 elementor-7290\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7829c09 e-flex e-con-boxed e-con e-parent\" data-id=\"7829c09\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4f84df2 e-con-full e-flex e-con e-child\" data-id=\"4f84df2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a0dbb08 elementor-widget elementor-widget-text-editor\" data-id=\"a0dbb08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Patrick Wirth diventa il nuovo direttore finanziario e Delia Gilgen assume il ruolo di responsabile dell&#8217;assistenza clienti.  <br><\/strong><strong>Parcandi AG non vede l&#8217;ora di lavorare con loro e augura a Delia e Patrick un grande successo!<\/strong><\/p><p>C\u00e9dric Wichert si \u00e8 unito al team del progetto nel 2020 durante la fase di pre-fondazione e ha svolto un ruolo chiave nella creazione e nella configurazione dei dipartimenti di Finanza e Assistenza clienti e ha co-fondato Parcandi AG nel 2021.<\/p><p>C\u00e9dric ha contribuito a facilitare la nostra crescita durante questo periodo e ha fatto in modo che le operazioni fossero sempre in grado di soddisfare le richieste che ne derivavano. C\u00e9dric Wichert ha deciso di cercare una nuova sfida professionale. Desideriamo ringraziarlo per il suo grande contributo e il suo straordinario impegno e gli auguriamo il meglio per il futuro.  <\/p><p>Patrick Wirth ha un&#8217;esperienza pluriennale nel campo della finanza e dei finanziamenti come CFO in diverse aziende e in precedenza ha costruito l&#8217;ecosistema della mobilit\u00e0 del Gruppo Baloise, tra le altre cose. Patrick \u00e8 stato quindi un sostenitore di Parcandi fin dalla sua nascita e ha fatto parte del Consiglio di Amministrazione fino a poco tempo fa. <\/p><p>In qualit\u00e0 di CFO di Parcandi AG, Patrick Wirth continua il suo impegno annuale a favore delle aziende emergenti nel settore della mobilit\u00e0. &#8220;Parcandi \u00e8 sinonimo di mobilit\u00e0 nuova e sostenibile nelle nostre citt\u00e0, con forza innovativa e tanta passione. Sono lieto di poter contribuire con la mia esperienza imprenditoriale in veste operativa e di dare forma al prossimo capitolo insieme al team&#8221;, afferma Patrick Wirth. <\/p><p>Delia Gilgen \u00e8 un&#8217;economista aziendale e in precedenza \u00e8 stata responsabile del Community Management di Working Bicycle AG. Ha una vasta esperienza nella creazione e nell&#8217;ottimizzazione di processi orientati al cliente in aziende giovani. <\/p><p>In qualit\u00e0 di Customer Operations Manager di Parcandi AG, Delia Gilgen \u00e8 ora attivamente coinvolta nella creazione dell&#8217;esperienza del cliente, dall&#8217;analisi e dall&#8217;implementazione di processi efficienti al controllo della qualit\u00e0. &#8220;Ci\u00f2 che mi entusiasma di Parcandi \u00e8 la combinazione di un approccio innovativo e sostenibile alla mobilit\u00e0 e l&#8217;opportunit\u00e0 di contribuire a dare forma alle cose come parte di un team dedicato&#8221;, afferma Delia Gilgen. <\/p><p>Non vediamo l&#8217;ora di lavorare con Delia Gilgen e Patrick Wirth e auguriamo loro ogni successo nei loro nuovi ruoli!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Parcandi si aggiudica la gara d&#8217;appalto 2022 dell&#8217;Ufficio di coordinamento per la mobilit\u00e0 sostenibile (KOMO). KOMO sostiene soluzioni di mobilit\u00e0 sostenibile che rafforzano modalit\u00e0 di trasporto rispettose dell&#8217;ambiente e delle risorse.<\/p>\n","protected":false},"author":2,"featured_media":7308,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_angie_page":false,"page_builder":"","footnotes":""},"categories":[46,45,39],"tags":[213,214,212],"sp_smart_badges":[],"class_list":["post-7293","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-storie","category-media-it","category-non-categorizzato","tag-cedric-wichert","tag-crescita-del-team","tag-dipendenti"],"acf":[],"_links":{"self":[{"href":"https:\/\/info.parcandi.ch\/it\/wp-json\/wp\/v2\/posts\/7293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/info.parcandi.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/info.parcandi.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/info.parcandi.ch\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/info.parcandi.ch\/it\/wp-json\/wp\/v2\/comments?post=7293"}],"version-history":[{"count":6,"href":"https:\/\/info.parcandi.ch\/it\/wp-json\/wp\/v2\/posts\/7293\/revisions"}],"predecessor-version":[{"id":12556,"href":"https:\/\/info.parcandi.ch\/it\/wp-json\/wp\/v2\/posts\/7293\/revisions\/12556"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/info.parcandi.ch\/it\/wp-json\/wp\/v2\/media\/7308"}],"wp:attachment":[{"href":"https:\/\/info.parcandi.ch\/it\/wp-json\/wp\/v2\/media?parent=7293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/info.parcandi.ch\/it\/wp-json\/wp\/v2\/categories?post=7293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/info.parcandi.ch\/it\/wp-json\/wp\/v2\/tags?post=7293"},{"taxonomy":"sp_smart_badges","embeddable":true,"href":"https:\/\/info.parcandi.ch\/it\/wp-json\/wp\/v2\/sp_smart_badges?post=7293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}